{"id":4371,"date":"2023-05-05T18:52:40","date_gmt":"2023-05-05T16:52:40","guid":{"rendered":"https:\/\/hydromot.lu\/techblog\/valves-hydrauliques\/"},"modified":"2023-10-23T08:19:48","modified_gmt":"2023-10-23T06:19:48","slug":"valves-hydrauliques","status":"publish","type":"page","link":"https:\/\/www.hydromot.lu\/techblog\/fr\/valves-hydrauliques\/","title":{"rendered":"Valves hydrauliques"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4371\" class=\"elementor elementor-4371 elementor-3973\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dba035f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dba035f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-739b1f6\" data-id=\"739b1f6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a65e4e0 elementor-widget elementor-widget-heading\" data-id=\"a65e4e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-xl\">Valves hydrauliques : types, fonctions et applications\n<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e161ab6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e161ab6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-466bf93\" data-id=\"466bf93\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ee55fac elementor-widget elementor-widget-text-editor\" data-id=\"ee55fac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Valves hydrauliques &#8211; Sans valves, rien ne fonctionne (ou presque) dans une installation hydraulique. Peu importe qu&#8217;il s&#8217;agisse de commuter un consommateur, de maintenir une charge ou d&#8217;actionner une ligne de commande.  <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Les valves hydrauliques jouent donc un r\u00f4le important dans les syst\u00e8mes hydrauliques, car elles contr\u00f4lent et r\u00e9gulent le flux d&#8217;huile hydraulique. Ils sont capables de r\u00e9guler diff\u00e9rentes fonctions comme le d\u00e9marrage, l&#8217;arr\u00eat, le changement de direction et le r\u00e9glage de la pression ou du d\u00e9bit du fluide hydraulique. C&#8217;est pourquoi les valves hydrauliques sont d&#8217;une importance capitale pour le fonctionnement pr\u00e9cis et fiable des installations hydrauliques.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-386bb21 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"386bb21\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-70a04fe\" data-id=\"70a04fe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5aef724 elementor-toc--minimized-on-tablet elementor-widget elementor-widget-table-of-contents\" data-id=\"5aef724\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;exclude_headings_by_selector&quot;:[],&quot;headings_by_tags&quot;:[&quot;h2&quot;,&quot;h3&quot;,&quot;h4&quot;,&quot;h5&quot;,&quot;h6&quot;],&quot;marker_view&quot;:&quot;numbers&quot;,&quot;no_headings_message&quot;:&quot;Aucun titre n\\u2019a \\u00e9t\\u00e9 trouv\\u00e9 sur cette page.&quot;,&quot;minimize_box&quot;:&quot;yes&quot;,&quot;minimized_on&quot;:&quot;tablet&quot;,&quot;hierarchical_view&quot;:&quot;yes&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__header\">\n\t\t\t\t\t\t<h4 class=\"elementor-toc__header-title\">\n\t\t\t\tContenu :\t\t\t<\/h4>\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--expand\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__5aef724\" aria-expanded=\"true\" aria-label=\"Ouvrir la table des mati\u00e8res\"><i aria-hidden=\"true\" class=\"fas fa-chevron-down\"><\/i><\/div>\n\t\t\t\t<div class=\"elementor-toc__toggle-button elementor-toc__toggle-button--collapse\" role=\"button\" tabindex=\"0\" aria-controls=\"elementor-toc__5aef724\" aria-expanded=\"true\" aria-label=\"Fermer la table des mati\u00e8res\"><i aria-hidden=\"true\" class=\"fas fa-chevron-up\"><\/i><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"elementor-toc__5aef724\" class=\"elementor-toc__body\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<i class=\"elementor-toc__spinner eicon-animation-spin eicon-loading\" aria-hidden=\"true\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d33260 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d33260\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ac4d903\" data-id=\"ac4d903\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be76990 elementor-widget elementor-widget-heading\" data-id=\"be76990\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Fonctionnement d'une vanne hydraulique<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d638f99 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d638f99\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1b3cb8f\" data-id=\"1b3cb8f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3eb558 elementor-widget elementor-widget-text-editor\" data-id=\"a3eb558\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Le fonctionnement d&#8217;une valve hydraulique d\u00e9pend du type de valve. Il existe deux types principaux de valves hydrauliques : Les valves \u00e0 tiroir et les valves \u00e0 si\u00e8ge.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Les distributeurs \u00e0 tiroir utilisent g\u00e9n\u00e9ralement un piston de commande comme \u00e9l\u00e9ment de contr\u00f4le. Ce piston se d\u00e9place \u00e0 l&#8217;int\u00e9rieur d&#8217;un al\u00e9sage dans le corps de la vanne. La position du piston \u00e0 l&#8217;int\u00e9rieur de l&#8217;al\u00e9sage d\u00e9termine si la connexion entre les canaux dans le corps de la vanne est ouverte ou ferm\u00e9e. Le piston de commande est guid\u00e9 dans le bo\u00eetier avec un jeu tr\u00e8s faible, le film liquide qui se forme entre les composants r\u00e9duit les frottements (voir aussi \u00e0 ce sujet <a href=\"https:\/\/hydromot.lu\/techblog\/fr\/valeur-de-brugger\/\" target=\"_blank\" rel=\"noopener\">la valeur Brugger<\/a>). Les distributeurs \u00e0 tiroir sont souvent utilis\u00e9s dans les vannes directionnelles.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-050e1c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"050e1c3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b3814c2\" data-id=\"b3814c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bb077d elementor-widget elementor-widget-image\" data-id=\"2bb077d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"212\" src=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Schieberventil-768x212.png\" class=\"attachment-medium_large size-medium_large wp-image-3980\" alt=\"Hydraulikventil Kolben eines Schieberventils\" srcset=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Schieberventil-768x212.png 768w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Schieberventil-300x83.png 300w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Schieberventil.png 1024w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cc7e14b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc7e14b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c947025\" data-id=\"c947025\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2785f5b elementor-widget elementor-widget-text-editor\" data-id=\"2785f5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Contrairement aux vannes \u00e0 tiroir, les vannes \u00e0 si\u00e8ge ont comme \u00e9l\u00e9ment de commande un composant tel qu&#8217;une bille, un c\u00f4ne ou une assiette. Cette pi\u00e8ce est press\u00e9e par un ressort sur le si\u00e8ge de la soupape afin de fermer ou d&#8217;ouvrir le couvercle de la soupape. Normalement, le canal s&#8217;ouvre contre la force du ressort lorsque le fluide hydraulique s&#8217;\u00e9coule. Les vannes \u00e0 si\u00e8ge sont particuli\u00e8rement \u00e9tanches par rapport aux vannes \u00e0 tiroir. C&#8217;est pourquoi ils sont utilis\u00e9s de pr\u00e9f\u00e9rence lorsque les circuits hydrauliques doivent \u00eatre ferm\u00e9s sans fuite. Les vannes d&#8217;arr\u00eat telles que les limiteurs de pression ou les clapets anti-retour sont des exemples de vannes \u00e0 si\u00e8ge.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e415ccb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e415ccb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e968e14\" data-id=\"e968e14\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c590bb elementor-widget elementor-widget-image\" data-id=\"3c590bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"260\" src=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/HMV-RV04BSP_Dim-768x260.jpg\" class=\"attachment-medium_large size-medium_large wp-image-3986\" alt=\"Hydraulikventil R\u00fcckschlagventil\" srcset=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/HMV-RV04BSP_Dim-768x260.jpg 768w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/HMV-RV04BSP_Dim-300x102.jpg 300w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/HMV-RV04BSP_Dim.jpg 774w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c17ef01 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c17ef01\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ce90e6b\" data-id=\"ce90e6b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-395161a elementor-widget elementor-widget-heading\" data-id=\"395161a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Valves hydrauliques - Types de construction\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ee8b4ba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ee8b4ba\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-978f028\" data-id=\"978f028\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-346637d elementor-widget elementor-widget-text-editor\" data-id=\"346637d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Les valves hydrauliques doivent r\u00e9pondre \u00e0 des exigences \u00e9lev\u00e9es dans les installations hydrauliques. C&#8217;est pourquoi il existe diff\u00e9rents types de valves hydrauliques avec diff\u00e9rentes m\u00e9thodes de montage. En principe, on peut distinguer les types de valves hydrauliques comme suit :<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Vannes pour montage en ligne<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Vannes pour montage sur plaque (par ex. CETOP5)<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Vannes \u00e0 plaque interm\u00e9diaire<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Vannes monobloc<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Vannes \u00e0 visser (\u00e9galement appel\u00e9es vannes \u00e0 cartouche) pour le montage en bloc<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Vannes en forme de disque  <\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Chaque mode de montage pr\u00e9sente des avantages et des domaines d&#8217;application sp\u00e9cifiques, en fonction des exigences de l&#8217;installation hydraulique.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-da522d4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"da522d4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e836760\" data-id=\"e836760\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-174f56f elementor-widget elementor-widget-heading\" data-id=\"174f56f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Vannes pour montage en ligne (vannes de tuyauterie)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7737314 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7737314\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2dce348\" data-id=\"2dce348\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53d6bab elementor-widget elementor-widget-text-editor\" data-id=\"53d6bab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les valves pour conduites, \u00e9galement appel\u00e9es valves pour montage en ligne, sont mont\u00e9es directement dans les conduites hydrauliques et servent d&#8217;\u00e9l\u00e9ments interm\u00e9diaires. Ce type de valves hydrauliques dispose de raccords filet\u00e9s qui se fixent sur les tubes hydrauliques ou les tuyaux flexibles \u00e0 l&#8217;aide de raccords \u00e0 visser.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55208c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55208c3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-44803e8\" data-id=\"44803e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad160bc elementor-widget elementor-widget-image\" data-id=\"ad160bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"177\" src=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/HMV_2-300x177.jpg\" class=\"attachment-medium size-medium wp-image-3992\" alt=\"R\u00fcckschlagventil in Rohrleitungsbauweise\" srcset=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/HMV_2-300x177.jpg 300w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/HMV_2-1024x605.jpg 1024w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/HMV_2-768x453.jpg 768w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/HMV_2.jpg 1470w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8551f5e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8551f5e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-13b5462\" data-id=\"13b5462\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9824b7 elementor-widget elementor-widget-heading\" data-id=\"f9824b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Vannes CETOP (structure de la plaque)\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d88d985 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d88d985\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3d8c323\" data-id=\"3d8c323\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e22330e elementor-widget elementor-widget-text-editor\" data-id=\"e22330e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les valves hydrauliques pour le montage sur plaque peuvent \u00eatre viss\u00e9es soit comme valve individuelle sur une plaque de raccordement (plaque de base de la valve), soit comme partie d&#8217;une plaque en s\u00e9rie. Ces valves peuvent \u00e9galement \u00eatre utilis\u00e9es comme composant sup\u00e9rieur d&#8217;un encha\u00eenement en hauteur, par exemple pour les groupes hydrauliques. En r\u00e8gle g\u00e9n\u00e9rale, les vannes pour montage sur plaque sont des vannes dites <a href=\"https:\/\/www.cetop.org\/\" target=\"_blank\" rel=\"noopener\">CETOP-vannes<\/a>, qui pr\u00e9sentent des trous de raccordement normalis\u00e9s (voir ISO 4401) et une construction de plaque standardis\u00e9e. Cela permet un montage extr\u00eamement peu encombrant. Il s&#8217;agit de ce que l&#8217;on appelle des <a href=\"https:\/\/hydromot.lu\/techblog\/fr\/electrovannes-fonctionnement-et-application\/\" target=\"_blank\" rel=\"noopener\">\u00e9lectrovannes<\/a>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-56d3a80 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"56d3a80\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fdc4409\" data-id=\"fdc4409\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-008c951 elementor-widget elementor-widget-image\" data-id=\"008c951\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"318\" src=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/04\/Magnetventil_Dekobild_front.jpg\" class=\"attachment-large size-large wp-image-3854\" alt=\"Dekobild Magnetventil front\" srcset=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/04\/Magnetventil_Dekobild_front.jpg 650w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/04\/Magnetventil_Dekobild_front-300x147.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7fd3234 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7fd3234\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2ae7afd\" data-id=\"2ae7afd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-318de75 elementor-widget elementor-widget-heading\" data-id=\"318de75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Vannes \u00e0 plaque interm\u00e9diaire<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6562295 elementor-widget elementor-widget-text-editor\" data-id=\"6562295\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ces valves se pr\u00e9sentent sous la forme de plaques qui sont install\u00e9es entre la plaque de base de la valve et la valve sup\u00e9rieure du cha\u00eenage en hauteur afin de contr\u00f4ler le flux hydraulique.  <br \/>Les vannes \u00e0 plaque interm\u00e9diaire ont des surfaces de raccordement aussi bien en haut qu&#8217;en bas. Les vannes sont travers\u00e9es \u00e0 la fois par des trous de raccordement et par des trous de fixation. Cela signifie que plusieurs vannes peuvent \u00eatre assembl\u00e9es dans un m\u00eame module pour remplir une s\u00e9rie de fonctions. En r\u00e8gle g\u00e9n\u00e9rale, ce type de vanne est utilis\u00e9 pour les encha\u00eenements verticaux.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4b3b5ad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4b3b5ad\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-41ecad2\" data-id=\"41ecad2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70bf93b elementor-widget elementor-widget-image\" data-id=\"70bf93b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"267\" height=\"300\" src=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Zwischenplatte_Mengenregler_NG6-267x300.jpg\" class=\"attachment-medium size-medium wp-image-4007\" alt=\"Hydraulikventil Mengenregler als Zwischenplattenventil\" srcset=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Zwischenplatte_Mengenregler_NG6-267x300.jpg 267w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Zwischenplatte_Mengenregler_NG6.jpg 650w\" sizes=\"(max-width: 267px) 100vw, 267px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-addcb63 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"addcb63\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9bf0fda\" data-id=\"9bf0fda\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c214bdf elementor-widget elementor-widget-heading\" data-id=\"c214bdf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Vannes monobloc<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ef437ac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ef437ac\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-33c3d03\" data-id=\"33c3d03\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a2f08c3 elementor-widget elementor-widget-text-editor\" data-id=\"a2f08c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les vannes monobloc sont constitu\u00e9es d&#8217;un seul bloc de fonte. Ce bloc int\u00e8gre plusieurs trous de valve par lesquels l&#8217;huile hydraulique peut s&#8217;\u00e9couler. Chacune de ces vannes peut \u00eatre command\u00e9e ind\u00e9pendamment des autres.<\/p>\n<p><strong>Avantage :<\/strong> par rapport aux vannes sandwich, il y a moins de surfaces d&#8217;\u00e9tanch\u00e9it\u00e9. En outre, il n&#8217;y a pas d&#8217;influence due aux forces de traction.<\/p>\n<p><strong>Inconv\u00e9nient :<\/strong> \u00e9tant donn\u00e9 qu&#8217;elles sont constitu\u00e9es d&#8217;un seul bloc, un d\u00e9faut dans l&#8217;une des vannes peut entra\u00eener le remplacement de tout le bloc. De plus, par rapport aux vannes sandwich, seul un nombre limit\u00e9 de sections de vannes peut \u00eatre r\u00e9alis\u00e9.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-39a686f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"39a686f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e7b7377\" data-id=\"e7b7377\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e2338a3 elementor-widget elementor-widget-image\" data-id=\"e2338a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"267\" height=\"300\" src=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/MB4_1S4_18ES3_G4_M3_24VDC-267x300.jpg\" class=\"attachment-medium size-medium wp-image-4010\" alt=\"Monoblockventil mit elektrischer Ansteuerung\" srcset=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/MB4_1S4_18ES3_G4_M3_24VDC-267x300.jpg 267w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/MB4_1S4_18ES3_G4_M3_24VDC.jpg 650w\" sizes=\"(max-width: 267px) 100vw, 267px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-958c3f9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"958c3f9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66de2de\" data-id=\"66de2de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-745ca6b elementor-widget elementor-widget-heading\" data-id=\"745ca6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Valves \u00e0 visser (valves \u00e0 cartouche)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56fcdc5 elementor-widget elementor-widget-text-editor\" data-id=\"56fcdc5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dans le domaine de l&#8217;hydraulique, les valves \u00e0 visser sont une solution tr\u00e8s appr\u00e9ci\u00e9e pour le montage en bloc des valves hydrauliques. Contrairement \u00e0 d&#8217;autres types de vannes qui sont viss\u00e9es sur une embase de vanne ou une plaque de rang\u00e9e, les vannes \u00e0 visser sont directement viss\u00e9es dans le trou de vissage du bloc de commande ou du bo\u00eetier.  <br \/>Le trou \u00e0 visser, \u00e9galement appel\u00e9 cavit\u00e9, contient le filetage de fixation central ainsi que les raccords hydrauliques. En fonction de la version de la vanne, le trou de vissage met \u00e9galement \u00e0 disposition des surfaces d&#8217;\u00e9tanch\u00e9it\u00e9 correspondantes. De nombreux fabricants de blocs de commande utilisent l&#8217;al\u00e9sage \u00e0 visser pour monter les composants hydrauliques directement dans le bloc et minimiser ainsi l&#8217;espace n\u00e9cessaire.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b06f963 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b06f963\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ae1391\" data-id=\"7ae1391\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b8c657 elementor-widget elementor-widget-image\" data-id=\"3b8c657\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"312\" height=\"350\" src=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/FR-13A-20-A-L_Gal.jpg\" class=\"attachment-medium_large size-medium_large wp-image-4004\" alt=\"Hydraulikventil Cartridge\" srcset=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/FR-13A-20-A-L_Gal.jpg 312w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/FR-13A-20-A-L_Gal-267x300.jpg 267w\" sizes=\"(max-width: 312px) 100vw, 312px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b47ae8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b47ae8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-06a66ec\" data-id=\"06a66ec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71858b6 elementor-widget elementor-widget-heading\" data-id=\"71858b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Valves hydrauliques en forme de disque<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-671a830 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"671a830\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2f24974\" data-id=\"2f24974\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2565f75 elementor-widget elementor-widget-text-editor\" data-id=\"2565f75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dans ce type de construction, il est possible de combiner des fonctions individuelles ou des plaques de vanne afin de permettre une multitude de fonctions de commande dans un module compact. Chaque &#8220;plaque&#8221; ou &#8220;disque&#8221; contient la fonction sp\u00e9cifique requise par les diff\u00e9rents circuits de contr\u00f4le.<\/p>\n<p>Ce type de vanne est tr\u00e8s modulaire, ce qui signifie qu&#8217;elles peuvent \u00eatre con\u00e7ues sur mesure pour des applications sp\u00e9cifiques. Les plaques de vanne sont g\u00e9n\u00e9ralement mont\u00e9es et serr\u00e9es \u00e0 l&#8217;aide de tirants ou de boulons afin de garantir une construction s\u00fbre et stable.<\/p>\n<p>Ces valves sont souvent utilis\u00e9es dans des applications qui n\u00e9cessitent une grande flexibilit\u00e9 et une grande adaptabilit\u00e9, comme les applications hydrauliques mobiles ou les syst\u00e8mes hydrauliques industriels complexes.  <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d750349 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d750349\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5048454\" data-id=\"5048454\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-07a26fe elementor-widget elementor-widget-image\" data-id=\"07a26fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"267\" height=\"300\" src=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Proportionalventil_1-267x300.jpg\" class=\"attachment-medium size-medium wp-image-4025\" alt=\"Hydraulikventil Sektionalventil\" srcset=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Proportionalventil_1-267x300.jpg 267w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Proportionalventil_1.jpg 650w\" sizes=\"(max-width: 267px) 100vw, 267px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9fa8416 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9fa8416\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d2af75c\" data-id=\"d2af75c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46f6860 elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"46f6860\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2022\/01\/Lager-Hydromot-1.jpg);\" role=\"img\" aria-label=\"Hydraulikmotoren Lager Hydromot\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tAcheter directement des valves hydrauliques dans notre boutique\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\t<p>Dans notre boutique hydraulique, vous trouverez un grand choix de valves hydrauliques. Rendez-nous visite et profitez de notre vaste portefeuille de produits.<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"https:\/\/www.hydromot.lu\/fr\/Vannes\/\" target=\"_blank\">\n\t\t\t\t\t\tCompte sur moi!\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6dfabc9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6dfabc9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-55d7b32\" data-id=\"55d7b32\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17f2c1d elementor-widget elementor-widget-heading\" data-id=\"17f2c1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Tous les articles sur les valves hydrauliques<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5bb7c78 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5bb7c78\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-802e9e8\" data-id=\"802e9e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Valves hydrauliques : types, fonctions et applications Valves hydrauliques &#8211; Sans valves, rien ne fonctionne (ou presque) dans une installation hydraulique. Peu importe qu&#8217;il s&#8217;agisse de commuter un consommateur, de maintenir une charge ou d&#8217;actionner une ligne de commande. Les valves hydrauliques jouent donc un r\u00f4le important dans les syst\u00e8mes hydrauliques, car elles contr\u00f4lent et&hellip;&nbsp;<a href=\"https:\/\/www.hydromot.lu\/techblog\/fr\/valves-hydrauliques\/\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">Valves hydrauliques<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1005,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-pagebuilder-full-width.php","meta":{"_crdt_document":"","neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"class_list":["post-4371","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.hydromot.lu\/techblog\/fr\/wp-json\/wp\/v2\/pages\/4371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hydromot.lu\/techblog\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hydromot.lu\/techblog\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hydromot.lu\/techblog\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hydromot.lu\/techblog\/fr\/wp-json\/wp\/v2\/comments?post=4371"}],"version-history":[{"count":7,"href":"https:\/\/www.hydromot.lu\/techblog\/fr\/wp-json\/wp\/v2\/pages\/4371\/revisions"}],"predecessor-version":[{"id":5792,"href":"https:\/\/www.hydromot.lu\/techblog\/fr\/wp-json\/wp\/v2\/pages\/4371\/revisions\/5792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hydromot.lu\/techblog\/fr\/wp-json\/wp\/v2\/media\/1005"}],"wp:attachment":[{"href":"https:\/\/www.hydromot.lu\/techblog\/fr\/wp-json\/wp\/v2\/media?parent=4371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}