{"id":1566,"date":"2022-03-23T13:39:29","date_gmt":"2022-03-23T12:39:29","guid":{"rendered":"https:\/\/hydromot.lu\/techblog\/pompes-hydrauliques\/pompes-a-engrenages\/"},"modified":"2023-10-27T08:41:35","modified_gmt":"2023-10-27T06:41:35","slug":"pompes-a-engrenages","status":"publish","type":"post","link":"https:\/\/www.hydromot.lu\/techblog\/fr\/pompes-a-engrenages\/","title":{"rendered":"pompes \u00e0 engrenages"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1566\" class=\"elementor elementor-1566 elementor-843\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f13cd85 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f13cd85\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-26015f3\" data-id=\"26015f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38e7ffd elementor-widget elementor-widget-heading\" data-id=\"38e7ffd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-xl\">Pompe \u00e0 engrenage hydraulique - 5 choses que vous devez savoir<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2485ff64 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2485ff64\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-35e82c34\" data-id=\"35e82c34\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e20c314 elementor-widget elementor-widget-text-editor\" data-id=\"e20c314\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Les pompes \u00e0 engrenages hydrauliques<\/strong> convertissent l&#8217;\u00e9nergie m\u00e9canique fournie en \u00e9nergie hydraulique. Une distinction est faite entre les pompes \u00e0 engrenages internes et externes.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-557b91c elementor-widget elementor-widget-table-of-contents\" data-id=\"557b91c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;exclude_headings_by_selector&quot;:[],&quot;headings_by_tags&quot;:[&quot;h2&quot;,&quot;h3&quot;,&quot;h4&quot;,&quot;h5&quot;,&quot;h6&quot;],&quot;marker_view&quot;:&quot;numbers&quot;,&quot;no_headings_message&quot;:&quot;Aucun titre n\\u2019a \\u00e9t\\u00e9 trouv\\u00e9 sur cette page.&quot;,&quot;min_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;min_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"table-of-contents.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-toc__header\">\n\t\t\t\t\t\t<div class=\"elementor-toc__header-title\">\n\t\t\t\tContenu\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"elementor-toc__557b91c\" class=\"elementor-toc__body\">\n\t\t\t<div class=\"elementor-toc__spinner-container\">\n\t\t\t\t<i class=\"elementor-toc__spinner eicon-animation-spin eicon-loading\" aria-hidden=\"true\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4f5738 elementor-widget elementor-widget-heading\" data-id=\"a4f5738\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-large\">Pompes \u00e0 engrenages internes - Silencieuses et efficaces<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ae55cc elementor-widget elementor-widget-text-editor\" data-id=\"3ae55cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-adae7dc elementor-widget elementor-widget-text-editor\" data-id=\"adae7dc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p>Les pompes <strong>\u00e0 engrenages internes<\/strong> sont particuli\u00e8rement silencieuses, ce qui est la caract\u00e9ristique la plus remarquable de ce type de pompe. Leur domaine d&#8217;application est donc principalement utilis\u00e9 dans l&#8217;hydraulique stationnaire (presses, machines de plasturgie, machines-outils, etc.). Ils sont \u00e9galement utilis\u00e9s dans les v\u00e9hicules qui travaillent dans des pi\u00e8ces ferm\u00e9es (par exemple, les chariots \u00e9l\u00e9vateurs \u00e9lectriques).<\/p>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-75a00c2 elementor-widget elementor-widget-heading\" data-id=\"75a00c2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n<div class=\"elementor-widget-container\"> <\/div>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8b3ab7 elementor-widget elementor-widget-heading\" data-id=\"d8b3ab7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Comment fonctionne une pompe hydraulique \u00e0 engrenages internes<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-140f420 elementor-widget elementor-widget-image\" data-id=\"140f420\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"319\" src=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Funktion-Innenzahnradpumpe.jpg\" class=\"attachment-medium_large size-medium_large wp-image-4110\" alt=\"Zahnradpumpe - Funktion Innenzahnradpumpe\" srcset=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Funktion-Innenzahnradpumpe.jpg 600w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Funktion-Innenzahnradpumpe-300x160.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Abb.1 Innenzahnradpumpe, Bosch Hydrauliktrainer Band 1<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b81199d elementor-widget elementor-widget-text-editor\" data-id=\"b81199d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0421ad elementor-widget elementor-widget-image\" data-id=\"c0421ad\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n<div class=\"elementor-widget-container\" style=\"text-align: left;\">\n<figure class=\"wp-caption alignnone\">Le rotor dent\u00e9 est reli\u00e9 \u00e0 la machine d&#8217;entra\u00eenement via l&#8217;arbre. Le volume entre les flancs des dents augmente \u00e0 mesure que le rotor dent\u00e9 et la couronne dent\u00e9e tournent. Cela aspire le fluide hydraulique.<\/figure>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-d0f4db6 elementor-widget elementor-widget-text-editor\" data-id=\"d0f4db6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p style=\"text-align: left;\">L&#8217;augmentation de volume a lieu \u00e0 un angle de rotation de 120\u00b0, ce qui signifie que la chambre de d\u00e9placement ne se remplit pas brusquement, mais relativement lentement. En raison de l&#8217;ouverture lente, la douceur de fonctionnement est particuli\u00e8rement \u00e9lev\u00e9e et le comportement d&#8217;aspiration est tr\u00e8s bon.<\/p>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-938227d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"938227d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d211deb\" data-id=\"d211deb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c5a8163 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c5a8163\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cd320b8\" data-id=\"cd320b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d9f846 elementor-widget elementor-widget-heading\" data-id=\"5d9f846\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-large\">Pompes \u00e0 engrenages externes - La conception la plus courante<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7568c21 elementor-widget elementor-widget-text-editor\" data-id=\"7568c21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Les pompes \u00e0 engrenages ext\u00e9rieurs<\/strong> sont des <a href=\"https:\/\/hydromot.lu\/techblog\/fr\/pompes-hydrauliques\/\" target=\"_blank\" rel=\"noopener\">pompes hydrauliques<\/a> produites en tr\u00e8s grandes quantit\u00e9s. Les raisons \u00e0 cela sont diverses :<\/p>\n<ul>\n<li>Gamme haute pression (jusqu&#8217;\u00e0 300 bar) avec un poids relativement faible<\/li>\n<li>Bas prix<\/li>\n<li>Grande plage de vitesse<\/li>\n<li>Peut \u00eatre utilis\u00e9 dans une large plage de temp\u00e9rature et de viscosit\u00e9<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f6b11fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f6b11fd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bf4eac2\" data-id=\"bf4eac2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7854606 elementor-widget elementor-widget-heading\" data-id=\"7854606\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-large\">Comment fonctionne une pompe \u00e0 engrenage externe ?<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aeecfdf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aeecfdf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d9b18bd\" data-id=\"d9b18bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74c24ff elementor-widget elementor-widget-text-editor\" data-id=\"74c24ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En termes de structure, la <strong>pompe \u00e0 engrenage externe<\/strong> est la solution la plus simple.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-36ce062 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"36ce062\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-049ac28\" data-id=\"049ac28\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d40b1d elementor-widget elementor-widget-image\" data-id=\"5d40b1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"301\" src=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Aussenzahnradpumpe-Aufbau.jpg\" class=\"attachment-large size-large wp-image-4104\" alt=\"Au\u00dfenzahnradpumpe Hydraulik - Aufbau und Schnittzeichnung\" srcset=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Aussenzahnradpumpe-Aufbau.jpg 600w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Aussenzahnradpumpe-Aufbau-300x151.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a8faab elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a8faab\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f5ddd67\" data-id=\"f5ddd67\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54f563d elementor-widget elementor-widget-text-editor\" data-id=\"54f563d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&#8217;engrenage sup\u00e9rieur (n\u00b0 7) est reli\u00e9 \u00e0 l&#8217;unit\u00e9 d&#8217;entra\u00eenement (moteur \u00e9lectrique, moteur \u00e0 combustion, engrenage de prise de force, etc.) via l&#8217;arbre d&#8217;entra\u00eenement et un embrayage (par exemple embrayage \u00e0 crabots ou embrayage \u00e0 engrenages).<\/p>\n<p>Les deux engrenages (7 et 8) sont positionn\u00e9s par les supports de palier (\u00e9galement appel\u00e9s brides de support) de telle mani\u00e8re que les engrenages s&#8217;engr\u00e8nent (engr\u00e8nement) avec un jeu minimal pendant la rotation. Les chambres de d\u00e9placement sont form\u00e9es entre les flancs des dents, le carter (paroi int\u00e9rieure) et les faces frontales des supports de palier.<\/p>\n<p>Le volume de liquide enferm\u00e9 dans un entredent est transport\u00e9 par la rotation de l&#8217;engrenage du c\u00f4t\u00e9 aspiration &#8220;S&#8221; et du c\u00f4t\u00e9 refoulement &#8220;P&#8221;, d\u00e9plac\u00e9 au point d&#8217;engagement des engrenages et press\u00e9 dans l&#8217;orifice de pression. Pour simplifier, l&#8217;augmentation de pression du c\u00f4t\u00e9 aspiration au c\u00f4t\u00e9 pression peut \u00eatre suppos\u00e9e lin\u00e9aire. En raison de cette r\u00e9partition lin\u00e9aire de la pression, des charges \u00e9lev\u00e9es sur l&#8217;arbre et les paliers se produisent. Le volume de d\u00e9placement g\u00e9om\u00e9trique est constant.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cde8db9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cde8db9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6a3f7de\" data-id=\"6a3f7de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17b2c9b elementor-widget elementor-widget-image\" data-id=\"17b2c9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"305\" src=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2022\/06\/Aufbau-hydraulische-Zahnradpumpe.jpg\" class=\"attachment-large size-large wp-image-1545\" alt=\"Aufbau einer Zahnradpumpe - Explosionsdarstellung\" srcset=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2022\/06\/Aufbau-hydraulische-Zahnradpumpe.jpg 600w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2022\/06\/Aufbau-hydraulische-Zahnradpumpe-300x153.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c160d0b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c160d0b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ae67aa0\" data-id=\"ae67aa0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c1704d elementor-widget elementor-widget-text-editor\" data-id=\"6c1704d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dans <strong>les pompes hydrauliques \u00e0 engrenages<\/strong> , les fuites d&#8217;huile sont caus\u00e9es par le jeu entre l&#8217;engrenage et le carter. Pour garantir que seule une tr\u00e8s petite quantit\u00e9 de liquide passe du c\u00f4t\u00e9 refoulement au c\u00f4t\u00e9 aspiration \u00e0 travers cet espace lorsque la pression augmente, le support de palier c\u00f4t\u00e9 couvercle est press\u00e9 contre les faces frontales des roues dent\u00e9es via un champ de pression axial. On parle aussi de <b>compensation de pression<\/b>. Il est possible d&#8217;atteindre des degr\u00e9s d&#8217;efficacit\u00e9 de 0,8 \u00e0 0,9.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e07c9c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e07c9c3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ce03ad\" data-id=\"1ce03ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d2177c5 elementor-widget elementor-widget-heading\" data-id=\"d2177c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-large\">Pompes \u00e0 engrenages - Application<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fa274a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fa274a9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1021fab\" data-id=\"1021fab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75c1393 elementor-widget elementor-widget-text-editor\" data-id=\"75c1393\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les domaines d&#8217;application typiques des pompes \u00e0 engrenages sont les machines de construction, les machines agricoles, les tracteurs, les groupes hydrauliques. Les pompes \u00e0 engrenages sont \u00e9galement fr\u00e9quemment utilis\u00e9es dans les machines \u00e0 fendre le bois, en particulier en liaison avec les entra\u00eenements \u00e0 prise de force.<\/p>\n<p>Les s\u00e9ries de pompes en aluminium les plus courantes sont les groupes 0,5, 1, 2, 3 et 4<\/p>\n<p>Les pompes \u00e0 engrenages peuvent \u00eatre combin\u00e9es en pompes doubles ou triples, diff\u00e9rents ensembles \u00e9tant alors possibles, par exemple la combinaison du groupe 3 avec le groupe 2, ou du BG2 avec le BG1, etc.  <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-757bb75 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"757bb75\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-23b24a7\" data-id=\"23b24a7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd369e0 elementor-widget elementor-widget-image\" data-id=\"dd369e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"756\" height=\"417\" src=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Zahnradpumpen.jpg\" class=\"attachment-medium_large size-medium_large wp-image-4119\" alt=\"Zwei Zahnradpumpen\" srcset=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Zahnradpumpen.jpg 756w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Zahnradpumpen-300x165.jpg 300w\" sizes=\"(max-width: 756px) 100vw, 756px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-16a184c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"16a184c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1348e79\" data-id=\"1348e79\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35fe646 elementor-widget elementor-widget-heading\" data-id=\"35fe646\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-large\">Calculer le d\u00e9bit d'une pompe \u00e0 engrenages d\u00e9fectueuse | formule<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6b064de elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6b064de\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-45876ce\" data-id=\"45876ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc99725 elementor-widget elementor-widget-text-editor\" data-id=\"bc99725\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cela arrive encore et encore&#8230; La pompe \u00e0 engrenages n&#8217;apporte plus de puissance et la d\u00e9monte de son tracteur ou de son groupe. On cherche d\u00e9sesp\u00e9r\u00e9ment la plaque signal\u00e9tique pour savoir exactement o\u00f9 se procurer la pi\u00e8ce de rechange correspondante. La seule chose stupide est si la plaque signal\u00e9tique est manquante et qu&#8217;il n&#8217;y a aucune indication du d\u00e9placement de la pompe. Il existe un moyen relativement simple de d\u00e9terminer la cylindr\u00e9e d&#8217;une pompe \u00e0 engrenages apr\u00e8s d\u00e9montage en utilisant la formule suivante :<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-afbfc4f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"afbfc4f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bafb395\" data-id=\"bafb395\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2974a9c elementor-widget elementor-widget-image\" data-id=\"2974a9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"80\" src=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/FormelZRP-300x80.jpg\" class=\"attachment-medium size-medium wp-image-4091\" alt=\"Formel zum Berechnen des Schluckvolumens einer Zahnradpumpe\" srcset=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/FormelZRP-300x80.jpg 300w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/FormelZRP.jpg 705w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-670c0d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"670c0d5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5decc6d\" data-id=\"5decc6d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ffed0fd elementor-widget elementor-widget-text-editor\" data-id=\"ffed0fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La dimension &#8220;W&#8221; est la largeur de l&#8217;engrenage, L est la largeur de la paire d&#8217;engrenages, &#8220;D&#8221; est le diam\u00e8tre d&#8217;un engrenage. Toutes les dimensions sont donn\u00e9es en cm afin d&#8217;obtenir directement le volume de refoulement en cm3\/tour.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-80038b1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"80038b1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-929c31d\" data-id=\"929c31d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b81cd77 elementor-widget elementor-widget-image\" data-id=\"b81cd77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"197\" src=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Zahnrad-300x197.jpg\" class=\"attachment-medium size-medium wp-image-4097\" alt=\"Zahnradpumpe - Schnittdarstellung Berechnung Schluckvolumen\" srcset=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Zahnrad-300x197.jpg 300w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Zahnrad.jpg 728w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9fe7e51 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9fe7e51\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-39903df\" data-id=\"39903df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48835f3 elementor-widget elementor-widget-text-editor\" data-id=\"48835f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Apr\u00e8s avoir d\u00e9termin\u00e9 les dimensions W, D et L, la cylindr\u00e9e de la pompe peut \u00eatre calcul\u00e9e \u00e0 l&#8217;aide de la formule ci-dessus.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-574d7db elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"574d7db\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b419895\" data-id=\"b419895\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c190ae elementor-widget elementor-widget-heading\" data-id=\"6c190ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-large\">Inversion du sens de rotation d'une pompe \u00e0 engrenage<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f6e0ff6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f6e0ff6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-353dfbb\" data-id=\"353dfbb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d465cb7 elementor-widget elementor-widget-text-editor\" data-id=\"d465cb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dans certains cas pratiques, il est n\u00e9cessaire d&#8217;inverser le <strong>sens de rotation d&#8217;une pompe \u00e0 engrenages<\/strong> . Exemple : on a utilis\u00e9 une <strong>pompe tournant \u00e0 droite<\/strong> avec un multiplicateur sur une prise de force arri\u00e8re et on souhaite maintenant utiliser l&#8217;unit\u00e9 sur une prise de force avant. Le sens de rotation de la pompe doit alors \u00eatre chang\u00e9 de droite \u00e0 gauche.<\/p>\n<div class=\"elementor-element elementor-element-1998e6b elementor-widget elementor-widget-text-editor\" style=\"--listpad: 15px; --liststyle: disc; --flex-direction: initial; --flex-wrap: initial; --justify-content: initial; --align-items: initial; --align-content: initial; --gap: initial; --flex-basis: initial; --flex-grow: initial; --flex-shrink: initial; --order: initial; --align-self: initial; flex-basis: var(--flex-basis); flex-grow: var(--flex-grow); flex-shrink: var(--flex-shrink); order: var(--order); align-self: var(--align-self); flex-direction: var(--flex-direction); flex-wrap: var(--flex-wrap); justify-content: var(--justify-content); align-items: var(--align-items); align-content: var(--align-content); gap: var(--gap); --swiper-theme-color: #000; --swiper-navigation-size: 44px; --swiper-pagination-bullet-size: 6px; --swiper-pagination-bullet-horizontal-gap: 6px; --widgets-spacing: 20px; color: #0f0f0f; font-family: 'Fira Sans', sans-serif; font-weight: 400; margin-bottom: 20px;\" data-id=\"1998e6b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\" style=\"transition: background 0.3s,border 0.3s,border-radius 0.3s,box-shadow 0.3s,transform var(--e-transform-transition-duration,0.4s);\">\n<p>Le sens de rotation est g\u00e9n\u00e9ralement indiqu\u00e9 par une fl\u00e8che sur le bo\u00eetier. Pour indiquer le sens de rotation, regardez l&#8217;arbre de face :<\/p>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8254ee9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8254ee9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bd80e1d\" data-id=\"bd80e1d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c0bc3e elementor-widget elementor-widget-image\" data-id=\"4c0bc3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"111\" src=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Drehrichtungspfeile.png\" class=\"attachment-large size-large wp-image-4088\" alt=\"Drehrichtungspfeile einer Zahnradpumpe\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37b1191 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"37b1191\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5219908\" data-id=\"5219908\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9559654 elementor-widget elementor-widget-text-editor\" data-id=\"9559654\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div style=\"box-sizing: border-box; --flex-direction: initial; --flex-wrap: initial; --justify-content: initial; --align-items: initial; --align-content: initial; --gap: initial; --flex-basis: initial; --flex-grow: initial; --flex-shrink: initial; --order: initial; --align-self: initial; flex-basis: var(--flex-basis); flex-grow: var(--flex-grow); flex-shrink: var(--flex-shrink); order: var(--order); align-self: var(--align-self); flex-direction: var(--flex-direction); flex-wrap: var(--flex-wrap); justify-content: var(--justify-content); align-items: var(--align-items); align-content: var(--align-content); gap: var(--gap); position: relative; --swiper-theme-color: #000; --swiper-navigation-size: 44px; --swiper-pagination-bullet-size: 6px; --swiper-pagination-bullet-horizontal-gap: 6px; text-align: center; --widgets-spacing: 20px; margin-bottom: 20px; color: #0f0f0f; font-family: 'Fira Sans', sans-serif; font-size: 16px; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; font-weight: 400; letter-spacing: normal; orphans: 2; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; -webkit-text-stroke-width: 0px; background-color: #ffffff; text-decoration-thickness: initial; text-decoration-style: initial; text-decoration-color: initial;\" data-id=\"9c3327e\" data-element_type=\"widget\" data-widget_type=\"image.default\"> <\/div>\n<div style=\"box-sizing: border-box; --listpad: 15px; --liststyle: disc; --flex-direction: initial; --flex-wrap: initial; --justify-content: initial; --align-items: initial; --align-content: initial; --gap: initial; --flex-basis: initial; --flex-grow: initial; --flex-shrink: initial; --order: initial; --align-self: initial; flex-basis: var(--flex-basis); flex-grow: var(--flex-grow); flex-shrink: var(--flex-shrink); order: var(--order); align-self: var(--align-self); flex-direction: var(--flex-direction); flex-wrap: var(--flex-wrap); justify-content: var(--justify-content); align-items: var(--align-items); align-content: var(--align-content); gap: var(--gap); position: relative; --swiper-theme-color: #000; --swiper-navigation-size: 44px; --swiper-pagination-bullet-size: 6px; --swiper-pagination-bullet-horizontal-gap: 6px; --widgets-spacing: 20px; color: #0f0f0f; font-family: 'Fira Sans', sans-serif; font-weight: 400; margin-bottom: 20px; font-size: 16px; font-style: normal; font-variant-ligatures: normal; font-variant-caps: normal; letter-spacing: normal; orphans: 2; text-align: start; text-indent: 0px; text-transform: none; white-space: normal; widows: 2; word-spacing: 0px; -webkit-text-stroke-width: 0px; background-color: #ffffff; text-decoration-thickness: initial; text-decoration-style: initial; text-decoration-color: initial;\" data-id=\"1998e6b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div style=\"box-sizing: border-box; transition: background 0.3s,border 0.3s,border-radius 0.3s,box-shadow 0.3s,transform var(--e-transform-transition-duration,0.4s);\">\n<p style=\"box-sizing: border-box; margin: 0px 0px 30px; padding: 0px;\">L&#8217;inversion du sens de rotation se fait selon les instructions suivantes :<\/p>\n<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-768a620 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"768a620\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f02f022\" data-id=\"f02f022\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f76fa8d elementor-widget elementor-widget-image\" data-id=\"f76fa8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"414\" height=\"796\" src=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Drehrichtungsumkehr-einer-Zahnradpumpe.jpg\" class=\"attachment-large size-large wp-image-4107\" alt=\"Anleitung Drehrichtungsumkehr einer Zahnradpumpe\" srcset=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Drehrichtungsumkehr-einer-Zahnradpumpe.jpg 414w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Drehrichtungsumkehr-einer-Zahnradpumpe-156x300.jpg 156w\" sizes=\"(max-width: 414px) 100vw, 414px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cca8af7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cca8af7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-01a86e4\" data-id=\"01a86e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-002692c elementor-widget elementor-widget-text-editor\" data-id=\"002692c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La propret\u00e9 doit \u00eatre assur\u00e9e aussi bien lors du d\u00e9montage que <strong>du remontage de la pompe \u00e0 engrenages<\/strong> . Si des joints sont endommag\u00e9s lors des travaux de montage, ils doivent \u00eatre imm\u00e9diatement remplac\u00e9s par des joints neufs. De plus, lors du montage de la pompe \u00e0 engrenages, assurez-vous que les joints ne sont pas pinc\u00e9s. Les couples de <strong>serrage<\/strong> des vis du bo\u00eetier doivent \u00eatre respect\u00e9s.<\/p>\n<p>Une vid\u00e9o sur l&#8217;inversion du sens de rotation d&#8217;une pompe \u00e0 engrenages peut \u00eatre trouv\u00e9e ici :<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-66f0f05 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"66f0f05\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0c9dd23\" data-id=\"0c9dd23\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1630bfd elementor-widget elementor-widget-shortcode\" data-id=\"1630bfd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><iframe width=\"917\" height=\"516\" src=\"https:\/\/www.youtube.com\/embed\/UQpbQSJV1tI\" title=\"Hydraulik: Drehrichtungswechsel einer hydraulischen Zahnradpumpe\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4cb69d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4cb69d7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-17871d8\" data-id=\"17871d8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3afd338 elementor-widget elementor-widget-heading\" data-id=\"3afd338\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-large\">Pompe \u00e0 engrenages pour remorques de voiture - comment \u00e7a marche ?<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-16e101e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"16e101e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0b8131e\" data-id=\"0b8131e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce5e32e elementor-widget elementor-widget-text-editor\" data-id=\"ce5e32e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La question revient sans cesse : une <strong>pompe \u00e0 engrenages peut-elle fonctionner avec une visseuse sans fil<\/strong> ? La r\u00e9ponse est simple : oui, c&#8217;est possible.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1690d5f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1690d5f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4fe26b2\" data-id=\"4fe26b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84ba50d elementor-widget elementor-widget-image\" data-id=\"84ba50d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Akkuschrauber-zum-Antrieb-Zahnradpumpe-1-300x300.jpg\" class=\"attachment-medium size-medium wp-image-4101\" alt=\"Akkuschrauber zum Antrieb einer Zahnradpumpe\" srcset=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Akkuschrauber-zum-Antrieb-Zahnradpumpe-1-300x300.jpg 300w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Akkuschrauber-zum-Antrieb-Zahnradpumpe-1-150x150.jpg 150w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Akkuschrauber-zum-Antrieb-Zahnradpumpe-1.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b4430f1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b4430f1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a74ee2\" data-id=\"4a74ee2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c54257e elementor-widget elementor-widget-text-editor\" data-id=\"c54257e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En r\u00e8gle g\u00e9n\u00e9rale, <strong>des pompes hydrauliques \u00e0 engrenages<\/strong> du groupe 1 avec une cylindr\u00e9e de 3 \u00e0 3,5 cm\u00b3\/tr sont utilis\u00e9es. L&#8217;entra\u00eenement de la <strong>perceuse sans fil<\/strong> avec 18 volts et environ 41 amp\u00e8res d\u00e9veloppe une puissance d&#8217;environ 750 watts ou un couple compris entre 40 et 50 Nm (selon le fabricant). La vitesse de sortie de la visseuse sans fil est d&#8217;environ 1000 tr\/min au niveau 2. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-605b40f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"605b40f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-23d3d1a\" data-id=\"23d3d1a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b1ded2 elementor-widget elementor-widget-text-editor\" data-id=\"9b1ded2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cela donne la cylindr\u00e9e de la pompe :<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-52e83a5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"52e83a5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f6f3707\" data-id=\"f6f3707\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ebf923f elementor-widget elementor-widget-image\" data-id=\"ebf923f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"81\" src=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Formel-Foerdervolumen-Anhaengerpumpe-1024x81.png\" class=\"attachment-large size-large wp-image-4138\" alt=\"Formel zur Berechnung des F\u00f6rdervolumens einer Zahnradpumpe\" srcset=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Formel-Foerdervolumen-Anhaengerpumpe-1024x81.png 1024w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Formel-Foerdervolumen-Anhaengerpumpe-300x24.png 300w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Formel-Foerdervolumen-Anhaengerpumpe-768x61.png 768w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Formel-Foerdervolumen-Anhaengerpumpe-1536x121.png 1536w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Formel-Foerdervolumen-Anhaengerpumpe.png 1891w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9f315b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9f315b8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9035fc2\" data-id=\"9035fc2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-03e5b52 elementor-widget elementor-widget-text-editor\" data-id=\"03e5b52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Avec une puissance d&#8217;entra\u00eenement de 0,75 kW, la pression maximale est de :<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-abfd088 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"abfd088\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-19c9cb6\" data-id=\"19c9cb6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f43f814 elementor-widget elementor-widget-image\" data-id=\"f43f814\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"87\" src=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Formel-Druck-Anhaengerpumpe-1024x87.png\" class=\"attachment-large size-large wp-image-4135\" alt=\"Druckberechnung Hydraulik Zahnradpumpe\" srcset=\"https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Formel-Druck-Anhaengerpumpe-1024x87.png 1024w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Formel-Druck-Anhaengerpumpe-300x25.png 300w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Formel-Druck-Anhaengerpumpe-768x65.png 768w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Formel-Druck-Anhaengerpumpe-1536x130.png 1536w, https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2023\/05\/Formel-Druck-Anhaengerpumpe.png 1891w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f0d9b7d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f0d9b7d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dc4e1f8\" data-id=\"dc4e1f8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27472cd elementor-widget elementor-widget-text-editor\" data-id=\"27472cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cela permet d&#8217;actionner sans probl\u00e8me des pompes hydrauliques avec une visseuse sans fil.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f2d7667 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f2d7667\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d33ff77\" data-id=\"d33ff77\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f76ca0d elementor-widget elementor-widget-text-editor\" data-id=\"f76ca0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-217014a elementor-widget elementor-widget-text-editor\" data-id=\"217014a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p>Une application typique est la <strong>conversion<\/strong> d&#8217;une <strong>remorque inclinable hydrauliquement<\/strong> \u00e0 l&#8217;aide d&#8217;une pompe \u00e0 main. La <strong>pompe \u00e0 main<\/strong> est remplac\u00e9e par une <strong>pompe \u00e0 engrenages<\/strong> et <strong>aliment\u00e9e par une visseuse sans fil<\/strong> . Il y a quelques points \u00e0 consid\u00e9rer lors de la conversion. Si vous avez des questions, veuillez nous <a href=\"https:\/\/www.hydromot.lu\/fr\/info\/Service-de-rappel.html\">contacter<\/a> .<\/p>\n<\/div>\n<\/div>\n<div class=\"elementor-element elementor-element-a370d06 elementor-widget elementor-widget-button\" data-id=\"a370d06\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-button-wrapper\"> <\/div>\n<\/div>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0212a77 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0212a77\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e273845\" data-id=\"e273845\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-196457f elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"196457f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.hydromot.lu\/techblog\/wp-content\/uploads\/2022\/04\/Zahnradpumpe-Hydraulik.jpg);\" role=\"img\" aria-label=\"Zahnradpumpe Explosionsdarstellung Link zum Shop\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tCliquez ici pour les pompes \u00e0 engrenages dans notre magasin hydraulique !\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\t<p>Dans notre boutique en ligne, vous trouverez un grand choix de pompes hydrauliques \u00e0 engrenages. <\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"https:\/\/www.hydromot.lu\/fr\/Pompe-Hydraulique\/Pompes----engrenages---pompes-hydrauliques\/\" target=\"_blank\">\n\t\t\t\t\t\tVers la boutique hydraulique !\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Pompe \u00e0 engrenage hydraulique &#8211; 5 choses que vous devez savoir Les pompes \u00e0 engrenages hydrauliques convertissent l&#8217;\u00e9nergie m\u00e9canique fournie en \u00e9nergie hydraulique. Une distinction est faite entre les pompes \u00e0 engrenages internes et externes. Contenu Pompes \u00e0 engrenages internes &#8211; Silencieuses et efficaces Les pompes \u00e0 engrenages internes sont particuli\u00e8rement silencieuses, ce qui est&hellip;&nbsp;<a href=\"https:\/\/www.hydromot.lu\/techblog\/fr\/pompes-a-engrenages\/\" rel=\"bookmark\">Read More &raquo;<span class=\"screen-reader-text\">pompes \u00e0 engrenages<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":4119,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","neve_meta_sidebar":"right","neve_meta_container":"","neve_meta_enable_content_width":"on","neve_meta_content_width":75,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"[\"title\",\"meta\",\"content\",\"tags\"]","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"on","neve_meta_reading_time":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[51,52],"tags":[],"class_list":["post-1566","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hydraulic-pumps","category-pompes-hydrauliques"],"_links":{"self":[{"href":"https:\/\/www.hydromot.lu\/techblog\/fr\/wp-json\/wp\/v2\/posts\/1566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hydromot.lu\/techblog\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hydromot.lu\/techblog\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hydromot.lu\/techblog\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hydromot.lu\/techblog\/fr\/wp-json\/wp\/v2\/comments?post=1566"}],"version-history":[{"count":15,"href":"https:\/\/www.hydromot.lu\/techblog\/fr\/wp-json\/wp\/v2\/posts\/1566\/revisions"}],"predecessor-version":[{"id":5549,"href":"https:\/\/www.hydromot.lu\/techblog\/fr\/wp-json\/wp\/v2\/posts\/1566\/revisions\/5549"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hydromot.lu\/techblog\/fr\/wp-json\/wp\/v2\/media\/4119"}],"wp:attachment":[{"href":"https:\/\/www.hydromot.lu\/techblog\/fr\/wp-json\/wp\/v2\/media?parent=1566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hydromot.lu\/techblog\/fr\/wp-json\/wp\/v2\/categories?post=1566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hydromot.lu\/techblog\/fr\/wp-json\/wp\/v2\/tags?post=1566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}